{"id":3262,"date":"2026-05-26T15:09:59","date_gmt":"2026-05-26T14:09:59","guid":{"rendered":"https:\/\/www.ideolegal.com\/?p=3262"},"modified":"2026-05-26T15:09:59","modified_gmt":"2026-05-26T14:09:59","slug":"la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad","status":"publish","type":"post","link":"https:\/\/www.ideolegal.com\/en\/la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad\/","title":{"rendered":"La sujeci\u00f3n al IVA en los servicios prestados por socios profesionales a su sociedad"},"content":{"rendered":"<p><a href=\"https:\/\/confilegal.com\/20260525-dgt-iva-socios-profesionales-autonomos-societarios\/\">Confilegal, 25 de mayo de 2026<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Confilegal, 25 de mayo de 2026<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"class_list":["post-3262","post","type-post","status-publish","format-standard","hentry","category-derecho-tributario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La sujeci\u00f3n al IVA en los servicios prestados por socios profesionales a su sociedad - IDEO LEGAL Abogados especialistas en Derecho Financiero y Tributario en Madrid y M\u00e1laga<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ideolegal.com\/la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La sujeci\u00f3n al IVA en los servicios prestados por socios profesionales a su sociedad - IDEO LEGAL Abogados especialistas en Derecho Financiero y Tributario en Madrid y M\u00e1laga\" \/>\n<meta property=\"og:description\" content=\"Confilegal, 25 de mayo de 2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ideolegal.com\/la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad\/\" \/>\n<meta property=\"og:site_name\" content=\"IDEO LEGAL\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-26T14:09:59+00:00\" \/>\n<meta name=\"author\" content=\"Ideo Legal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ideo Legal\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad\\\/\"},\"author\":{\"name\":\"Ideo Legal\",\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/#\\\/schema\\\/person\\\/385e5b0d6dac23c4ee00e88a64c674f9\"},\"headline\":\"La sujeci\u00f3n al IVA en los servicios prestados por socios profesionales a su sociedad\",\"datePublished\":\"2026-05-26T14:09:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad\\\/\"},\"wordCount\":19,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/#organization\"},\"articleSection\":[\"Derecho Tributario\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad\\\/\",\"url\":\"https:\\\/\\\/www.ideolegal.com\\\/la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad\\\/\",\"name\":\"La sujeci\u00f3n al IVA en los servicios prestados por socios profesionales a su sociedad - IDEO LEGAL Abogados especialistas en Derecho Financiero y Tributario en Madrid y M\u00e1laga\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/#website\"},\"datePublished\":\"2026-05-26T14:09:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ideolegal.com\\\/la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ideolegal.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La sujeci\u00f3n al IVA en los servicios prestados por socios profesionales a su sociedad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/#website\",\"url\":\"https:\\\/\\\/www.ideolegal.com\\\/\",\"name\":\"IDEO LEGAL\",\"description\":\"Abogados especialistas en Derecho Financiero y Tributario en Madrid y M\u00e1laga\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ideolegal.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/#organization\",\"name\":\"IDEO LEGAL\",\"url\":\"https:\\\/\\\/www.ideolegal.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ideolegal.com\\\/wp-content\\\/uploads\\\/ideo_legal-logo-new.png\",\"contentUrl\":\"https:\\\/\\\/www.ideolegal.com\\\/wp-content\\\/uploads\\\/ideo_legal-logo-new.png\",\"width\":350,\"height\":86,\"caption\":\"IDEO LEGAL\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/#\\\/schema\\\/person\\\/385e5b0d6dac23c4ee00e88a64c674f9\",\"name\":\"Ideo Legal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8248456b70d3352af8951e364610e860d47b1097e0d5d04354f9702888f9b2cc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8248456b70d3352af8951e364610e860d47b1097e0d5d04354f9702888f9b2cc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8248456b70d3352af8951e364610e860d47b1097e0d5d04354f9702888f9b2cc?s=96&d=mm&r=g\",\"caption\":\"Ideo Legal\"},\"url\":\"https:\\\/\\\/www.ideolegal.com\\\/en\\\/author\\\/ngarcia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La sujeci\u00f3n al IVA en los servicios prestados por socios profesionales a su sociedad - IDEO LEGAL Abogados especialistas en Derecho Financiero y Tributario en Madrid y M\u00e1laga","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ideolegal.com\/la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad\/","og_locale":"en_US","og_type":"article","og_title":"La sujeci\u00f3n al IVA en los servicios prestados por socios profesionales a su sociedad - IDEO LEGAL Abogados especialistas en Derecho Financiero y Tributario en Madrid y M\u00e1laga","og_description":"Confilegal, 25 de mayo de 2026","og_url":"https:\/\/www.ideolegal.com\/la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad\/","og_site_name":"IDEO LEGAL","article_published_time":"2026-05-26T14:09:59+00:00","author":"Ideo Legal","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ideo Legal"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ideolegal.com\/la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad\/#article","isPartOf":{"@id":"https:\/\/www.ideolegal.com\/la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad\/"},"author":{"name":"Ideo Legal","@id":"https:\/\/www.ideolegal.com\/#\/schema\/person\/385e5b0d6dac23c4ee00e88a64c674f9"},"headline":"La sujeci\u00f3n al IVA en los servicios prestados por socios profesionales a su sociedad","datePublished":"2026-05-26T14:09:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ideolegal.com\/la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad\/"},"wordCount":19,"publisher":{"@id":"https:\/\/www.ideolegal.com\/#organization"},"articleSection":["Derecho Tributario"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.ideolegal.com\/la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad\/","url":"https:\/\/www.ideolegal.com\/la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad\/","name":"La sujeci\u00f3n al IVA en los servicios prestados por socios profesionales a su sociedad - IDEO LEGAL Abogados especialistas en Derecho Financiero y Tributario en Madrid y M\u00e1laga","isPartOf":{"@id":"https:\/\/www.ideolegal.com\/#website"},"datePublished":"2026-05-26T14:09:59+00:00","breadcrumb":{"@id":"https:\/\/www.ideolegal.com\/la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ideolegal.com\/la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ideolegal.com\/la-sujecion-al-iva-en-los-servicios-prestados-por-socios-profesionales-a-su-sociedad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ideolegal.com\/en\/"},{"@type":"ListItem","position":2,"name":"La sujeci\u00f3n al IVA en los servicios prestados por socios profesionales a su sociedad"}]},{"@type":"WebSite","@id":"https:\/\/www.ideolegal.com\/#website","url":"https:\/\/www.ideolegal.com\/","name":"IDEO LEGAL","description":"Abogados especialistas en Derecho Financiero y Tributario en Madrid y M\u00e1laga","publisher":{"@id":"https:\/\/www.ideolegal.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ideolegal.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.ideolegal.com\/#organization","name":"IDEO LEGAL","url":"https:\/\/www.ideolegal.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ideolegal.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.ideolegal.com\/wp-content\/uploads\/ideo_legal-logo-new.png","contentUrl":"https:\/\/www.ideolegal.com\/wp-content\/uploads\/ideo_legal-logo-new.png","width":350,"height":86,"caption":"IDEO LEGAL"},"image":{"@id":"https:\/\/www.ideolegal.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ideolegal.com\/#\/schema\/person\/385e5b0d6dac23c4ee00e88a64c674f9","name":"Ideo Legal","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8248456b70d3352af8951e364610e860d47b1097e0d5d04354f9702888f9b2cc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8248456b70d3352af8951e364610e860d47b1097e0d5d04354f9702888f9b2cc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8248456b70d3352af8951e364610e860d47b1097e0d5d04354f9702888f9b2cc?s=96&d=mm&r=g","caption":"Ideo Legal"},"url":"https:\/\/www.ideolegal.com\/en\/author\/ngarcia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ideolegal.com\/en\/wp-json\/wp\/v2\/posts\/3262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ideolegal.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ideolegal.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ideolegal.com\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ideolegal.com\/en\/wp-json\/wp\/v2\/comments?post=3262"}],"version-history":[{"count":1,"href":"https:\/\/www.ideolegal.com\/en\/wp-json\/wp\/v2\/posts\/3262\/revisions"}],"predecessor-version":[{"id":3263,"href":"https:\/\/www.ideolegal.com\/en\/wp-json\/wp\/v2\/posts\/3262\/revisions\/3263"}],"wp:attachment":[{"href":"https:\/\/www.ideolegal.com\/en\/wp-json\/wp\/v2\/media?parent=3262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ideolegal.com\/en\/wp-json\/wp\/v2\/categories?post=3262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ideolegal.com\/en\/wp-json\/wp\/v2\/tags?post=3262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}