{"id":2775,"date":"2022-06-11T10:18:54","date_gmt":"2022-06-11T09:18:54","guid":{"rendered":"https:\/\/www.ideolegal.com\/?p=2775"},"modified":"2022-07-11T10:19:09","modified_gmt":"2022-07-11T09:19:09","slug":"retribucion-del-administrador-y-derecho-comunitario","status":"publish","type":"post","link":"https:\/\/www.ideolegal.com\/en\/retribucion-del-administrador-y-derecho-comunitario\/","title":{"rendered":"Retribuci\u00f3n del administrador y derecho comunitario"},"content":{"rendered":"<p style=\"text-align: right;\">Por Javier Mart\u00edn Fern\u00e1ndez<\/p>\n<p style=\"text-align: right;\">Publicado en <a href=\"https:\/\/cincodias.elpais.com\/cincodias\/2022\/06\/13\/opinion\/1655140493_163190.html\">Cinco D\u00edas<\/a>, el 14 de junio de 2022<\/p>\n<p><strong>Se pueden desarrollar de forma acumulativa las funciones de director, con relaci\u00f3n laboral, y administrador de la sociedad<\/strong><\/p>\n<p style=\"text-align: justify;\">La reciente sentencia del Tribunal de Justicia de la UE de 5 de mayo de 2022 concluye que los \u201cart\u00edculos 2, apartado 2, y 12, letras a) y c), de la Directiva 2008\/94\/CE del Parlamento Europeo y del Consejo, de 22 de octubre de 2008, relativa a la protecci\u00f3n de los trabajadores asalariados en caso de insolvencia del empresario, en su versi\u00f3n modificada por la Directiva (UE) 2015\/1794 del Parlamento Europeo y del Consejo, de 6 de octubre de 2015, deben interpretarse en el sentido de que se oponen a una jurisprudencia nacional seg\u00fan la cual una persona que ejerce, en virtud de un contrato de trabajo v\u00e1lido con arreglo al derecho nacional, de forma acumulativa las funciones de director y de miembro del \u00f3rgano estatutario de una sociedad mercantil no puede ser calificada de trabajador asalariado, en el sentido de dicha directiva, y, por lo tanto, no puede disfrutar de las garant\u00edas previstas por esa directiva\u201d.<\/p>\n<p style=\"text-align: justify;\">Parte el tribunal de que la directiva 2008\/94 no define, por s\u00ed misma, el concepto de \u201ctrabajador asalariado\u201d (apartado 33). Sin embargo, de su jurisprudencia anterior (STJUE de 5 de noviembre de 2014, T\u00fcmer, C 311\/13) se desprende que el margen de apreciaci\u00f3n de que disponen los Estados miembros no es ilimitado. De forma que ha de referirse, necesariamente, a una relaci\u00f3n que hace surgir un derecho del trabajador frente al empresario, consistente en exigir una remuneraci\u00f3n por el trabajo efectuado (apartado 35).<\/p>\n<div id=\"sm-it-main-container-1657530998407\" class=\"sm-it-main-container\" data-it=\"65a9d58f-5a83-4b7d-a319-35c5c36d5b07\" data-device=\"desktop\" data-index=\"0\">\n<div id=\"sm-reference-1657530998407\" class=\"sm-reference\">\n<p style=\"text-align: justify;\">De ello deduce que la circunstancia de que una persona que ejerce la funci\u00f3n de director de una sociedad mercantil sea tambi\u00e9n administrador de la misma no permite, por s\u00ed sola, presumir o excluir la existencia de una relaci\u00f3n laboral ni su calificaci\u00f3n como trabajador asalariado, en el sentido de la Directiva 2008\/94 (apartado 36).<\/p>\n<p style=\"text-align: justify;\">Finalmente, pese a que el p\u00e1rrafo primero del art\u00edculo 2.2 de la Directiva 2008\/94 permite a los Estados miembros adoptar las medidas necesarias para evitar abusos (apartado 39), es preciso recordar que estos \u00faltimos son pr\u00e1cticas abusivas que perjudican a las instituciones de garant\u00eda al crear artificialmente un cr\u00e9dito salarial y generar, de este modo, ilegalmente una obligaci\u00f3n de pago a cargo de estas instituciones (apartado 41).<\/p>\n<p style=\"text-align: justify;\">Consideramos que la sentencia del tribunal contiene una doctrina de aplicaci\u00f3n general, por la referencia que lleva a cabo a pronunciamientos anteriores, lo cual fuerza a reinterpretar, de un lado, el art\u00edculo 305 y concordantes del texto refundido de la Ley General de la Seguridad Social, sobre la extensi\u00f3n del r\u00e9gimen especial de los trabajadores por cuenta propia o aut\u00f3nomos. De otro, por lo que a nosotros interesa, la teor\u00eda del v\u00ednculo, aplicada al \u00e1mbito tributario, con la sentencia del Tribunal Supremo de 13 de noviembre de 2008 (recurso 2578\/2004), conocida como caso Mahou. Tal y como es bien conocido, la misma sostiene que toda retribuci\u00f3n que percibe un administrador de una sociedad lo es por el ejercicio de su cargo, salvo que se trate de dividendos. De forma m\u00e1s reciente, la sentencia del Supremo de 26 de febrero de 2018 (recurso de casaci\u00f3n 3574\/2017) analiza los art\u00edculos 217 y 249 del texto refundido de la Ley de Sociedades de Capital (TRLSC). Seg\u00fan el primero, el \u201ccargo de administrador es gratuito, a menos que los estatutos sociales establezcan lo contrario determinando el sistema de remuneraci\u00f3n\u201d (art\u00edculo 217.1), siendo la junta general quien fije su importe m\u00e1ximo anual (art\u00edculo 217.3), \u201cdentro del marco estatutario\u201d (art\u00edculo 249.bis.i). Por su parte, el art\u00edculo 249.3 dispone que cuando \u201cun miembro del consejo de administraci\u00f3n sea nombrado consejero delegado o se le atribuyan funciones ejecutivas en virtud de otro t\u00edtulo, ser\u00e1 necesario que se celebre un contrato entre este y la sociedad que deber\u00e1 ser aprobado previamente por el consejo de administraci\u00f3n con el voto favorable de las dos terceras partes de sus miembros\u201d.<\/p>\n<p style=\"text-align: justify;\">Pues bien, para el Tribunal Supremo, la atribuci\u00f3n al consejo de esta competencia \u201csupone el reconocimiento de un \u00e1mbito de autonom\u00eda \u2018dentro del marco estatutario\u2019 a que hace menci\u00f3n el art\u00edculo 249.bis.i TRSLC, que es el regulado con car\u00e1cter principal en el art\u00edculo 217 TRLSC, y dentro del importe m\u00e1ximo de la remuneraci\u00f3n anual del conjunto de los administradores que haya aprobado la junta general conforme prev\u00e9 el art\u00edculo 217.3 TRLSC\u201d. En definitiva, la previsi\u00f3n estatutaria de que el cargo de administrador es gratuito impide la aplicaci\u00f3n del art\u00edculo 249.3. Lo mismo ocurrir\u00eda si el importe pactado en el contrato fuera superior al aprobado por la junta general (de igual modo, las resoluciones del TEAC de 8 de octubre de 2019 y 17 de julio de 2020).<\/p>\n<p style=\"text-align: justify;\">Trasladando esta doctrina al \u00e1mbito tributario y por aplicaci\u00f3n del art\u00edculo 15.f) de la Ley del Impuesto sobre Sociedades (LIS), la AEAT viene considerando no deducible las retribuciones satisfechas por la realizaci\u00f3n de actividades que puedan considerarse como inherentes a la alta direcci\u00f3n (ejemplo: cualquier puesto directivo, como gerente o responsable de una unidad de negocio), ya que nos encontramos ante \u201cgastos de actuaciones contrarias al ordenamiento jur\u00eddico\u201d.<\/p>\n<p style=\"text-align: justify;\">En nuestra opini\u00f3n, esta interpretaci\u00f3n no resulta procedente, por dos razones. En primer lugar, la previsi\u00f3n del art\u00edculo 15.f) de la LIS no est\u00e1 pensada para estos casos, de conformidad con la STS de 8 de febrero de 2021 [recurso de casaci\u00f3n 3071\/2019 (FJ 4\u00ba)], pues la expresi\u00f3n \u201cactuaciones contrarias al ordenamiento jur\u00eddico\u201d se \u201cremite solo a cierto tipo de actuaciones, vg. sobornos y otras conductas similares\u201d.<\/p>\n<p style=\"text-align: justify;\">En segundo lugar, por la aplicaci\u00f3n de la doctrina plasmada en la sentencia del Tribunal de Justicia de la UE de 5 de mayo de 2022 a la que nos hemos referido al principio de estas l\u00edneas, contraria a la teor\u00eda del v\u00ednculo. En definitiva, cabe desarrollar, de forma acumulativa, funciones de director y de miembro del \u00f3rgano de administraci\u00f3n de una sociedad mercantil, siendo calificada la primera como una relaci\u00f3n laboral ajena al cargo. Ello nos fuerza a una reinterpretaci\u00f3n de los art\u00edculos 217 y 249 del TRLSC, concluyendo que el art\u00edculo 15.f) de la LIS resulta inaplicable en estos casos.<\/p>\n<p style=\"text-align: justify;\"><strong>Javier Mart\u00edn<\/strong> es Catedr\u00e1tico de Derecho Financiero y Tributario de la UCM y socio director de Ideo Legal<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La reciente sentencia del Tribunal de Justicia de la UE de 5 de mayo de 2022 concluye que los \u201cart\u00edculos 2, apartado 2, y 12, letras a) y c), de la Directiva 2008\/94\/CE del Parlamento Europeo y del Consejo, de 22 de octubre de 2008, relativa a la protecci\u00f3n de los trabajadores asalariados en caso de insolvencia del empresario, en su versi\u00f3n modificada por la Directiva (UE) 2015\/1794 del Parlamento Europeo y del Consejo, de 6 de octubre de 2015, deben interpretarse en el sentido de que se oponen a una jurisprudencia nacional seg\u00fan la cual una persona que ejerce, en virtud de un contrato de trabajo v\u00e1lido con arreglo al derecho nacional, de forma acumulativa las funciones de director y de miembro del \u00f3rgano estatutario de una sociedad mercantil no puede ser calificada de trabajador asalariado, en el sentido de dicha directiva, y, por lo tanto, no puede disfrutar de las garant\u00edas previstas por esa directiva\u201d.<\/p>\n","protected":false},"author":4,"featured_media":2045,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Retribuci\u00f3n del administrador y derecho comunitario - IDEO LEGAL Abogados especialistas en Derecho Financiero y Tributario en Madrid y M\u00e1laga<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ideolegal.com\/retribucion-del-administrador-y-derecho-comunitario\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retribuci\u00f3n del administrador y derecho comunitario - IDEO LEGAL Abogados especialistas en Derecho Financiero y Tributario en Madrid y M\u00e1laga\" \/>\n<meta property=\"og:description\" content=\"La reciente sentencia del Tribunal de Justicia de la UE de 5 de mayo de 2022 concluye que los \u201cart\u00edculos 2, apartado 2, y 12, letras a) y c), de la Directiva 2008\/94\/CE del Parlamento Europeo y del Consejo, de 22 de octubre de 2008, relativa a la protecci\u00f3n de los trabajadores asalariados en caso de insolvencia del empresario, en su versi\u00f3n modificada por la Directiva (UE) 2015\/1794 del Parlamento Europeo y del Consejo, de 6 de octubre de 2015, deben interpretarse en el sentido de que se oponen a una jurisprudencia nacional seg\u00fan la cual una persona que ejerce, en virtud de un contrato de trabajo v\u00e1lido con arreglo al derecho nacional, de forma acumulativa las funciones de director y de miembro del \u00f3rgano estatutario de una sociedad mercantil no puede ser calificada de trabajador asalariado, en el sentido de dicha directiva, y, por lo tanto, no puede disfrutar de las garant\u00edas previstas por esa directiva\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ideolegal.com\/retribucion-del-administrador-y-derecho-comunitario\/\" \/>\n<meta property=\"og:site_name\" content=\"IDEO LEGAL\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-11T09:18:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-11T09:19:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ideolegal.com\/wp-content\/uploads\/mision.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ideo Legal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ideo Legal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/retribucion-del-administrador-y-derecho-comunitario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/retribucion-del-administrador-y-derecho-comunitario\\\/\"},\"author\":{\"name\":\"Ideo Legal\",\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/#\\\/schema\\\/person\\\/ffc2742489f74493875a911a107a10df\"},\"headline\":\"Retribuci\u00f3n del administrador y derecho comunitario\",\"datePublished\":\"2022-06-11T09:18:54+00:00\",\"dateModified\":\"2022-07-11T09:19:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/retribucion-del-administrador-y-derecho-comunitario\\\/\"},\"wordCount\":1084,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/retribucion-del-administrador-y-derecho-comunitario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ideolegal.com\\\/wp-content\\\/uploads\\\/mision.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/retribucion-del-administrador-y-derecho-comunitario\\\/\",\"url\":\"https:\\\/\\\/www.ideolegal.com\\\/retribucion-del-administrador-y-derecho-comunitario\\\/\",\"name\":\"Retribuci\u00f3n del administrador y derecho comunitario - IDEO LEGAL Abogados especialistas en Derecho Financiero y Tributario en Madrid y M\u00e1laga\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/retribucion-del-administrador-y-derecho-comunitario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/retribucion-del-administrador-y-derecho-comunitario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ideolegal.com\\\/wp-content\\\/uploads\\\/mision.jpg\",\"datePublished\":\"2022-06-11T09:18:54+00:00\",\"dateModified\":\"2022-07-11T09:19:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/retribucion-del-administrador-y-derecho-comunitario\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ideolegal.com\\\/retribucion-del-administrador-y-derecho-comunitario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/retribucion-del-administrador-y-derecho-comunitario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ideolegal.com\\\/wp-content\\\/uploads\\\/mision.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ideolegal.com\\\/wp-content\\\/uploads\\\/mision.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"Ideo Legal\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/retribucion-del-administrador-y-derecho-comunitario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ideolegal.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retribuci\u00f3n del administrador y derecho comunitario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/#website\",\"url\":\"https:\\\/\\\/www.ideolegal.com\\\/\",\"name\":\"IDEO LEGAL\",\"description\":\"Abogados especialistas en Derecho Financiero y Tributario en Madrid y M\u00e1laga\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ideolegal.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/#organization\",\"name\":\"IDEO LEGAL\",\"url\":\"https:\\\/\\\/www.ideolegal.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ideolegal.com\\\/wp-content\\\/uploads\\\/ideo_legal-logo-new.png\",\"contentUrl\":\"https:\\\/\\\/www.ideolegal.com\\\/wp-content\\\/uploads\\\/ideo_legal-logo-new.png\",\"width\":350,\"height\":86,\"caption\":\"IDEO LEGAL\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ideolegal.com\\\/#\\\/schema\\\/person\\\/ffc2742489f74493875a911a107a10df\",\"name\":\"Ideo Legal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ebca4407bb57b0c9696bad57a7fe578bcde74bb5214811efd0a85629c7e224c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ebca4407bb57b0c9696bad57a7fe578bcde74bb5214811efd0a85629c7e224c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ebca4407bb57b0c9696bad57a7fe578bcde74bb5214811efd0a85629c7e224c?s=96&d=mm&r=g\",\"caption\":\"Ideo Legal\"},\"url\":\"https:\\\/\\\/www.ideolegal.com\\\/en\\\/author\\\/dcastro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retribuci\u00f3n del administrador y derecho comunitario - IDEO LEGAL Abogados especialistas en Derecho Financiero y Tributario en Madrid y M\u00e1laga","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ideolegal.com\/retribucion-del-administrador-y-derecho-comunitario\/","og_locale":"en_US","og_type":"article","og_title":"Retribuci\u00f3n del administrador y derecho comunitario - IDEO LEGAL Abogados especialistas en Derecho Financiero y Tributario en Madrid y M\u00e1laga","og_description":"La reciente sentencia del Tribunal de Justicia de la UE de 5 de mayo de 2022 concluye que los \u201cart\u00edculos 2, apartado 2, y 12, letras a) y c), de la Directiva 2008\/94\/CE del Parlamento Europeo y del Consejo, de 22 de octubre de 2008, relativa a la protecci\u00f3n de los trabajadores asalariados en caso de insolvencia del empresario, en su versi\u00f3n modificada por la Directiva (UE) 2015\/1794 del Parlamento Europeo y del Consejo, de 6 de octubre de 2015, deben interpretarse en el sentido de que se oponen a una jurisprudencia nacional seg\u00fan la cual una persona que ejerce, en virtud de un contrato de trabajo v\u00e1lido con arreglo al derecho nacional, de forma acumulativa las funciones de director y de miembro del \u00f3rgano estatutario de una sociedad mercantil no puede ser calificada de trabajador asalariado, en el sentido de dicha directiva, y, por lo tanto, no puede disfrutar de las garant\u00edas previstas por esa directiva\u201d.","og_url":"https:\/\/www.ideolegal.com\/retribucion-del-administrador-y-derecho-comunitario\/","og_site_name":"IDEO LEGAL","article_published_time":"2022-06-11T09:18:54+00:00","article_modified_time":"2022-07-11T09:19:09+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.ideolegal.com\/wp-content\/uploads\/mision.jpg","type":"image\/jpeg"}],"author":"Ideo Legal","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ideo Legal","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ideolegal.com\/retribucion-del-administrador-y-derecho-comunitario\/#article","isPartOf":{"@id":"https:\/\/www.ideolegal.com\/retribucion-del-administrador-y-derecho-comunitario\/"},"author":{"name":"Ideo Legal","@id":"https:\/\/www.ideolegal.com\/#\/schema\/person\/ffc2742489f74493875a911a107a10df"},"headline":"Retribuci\u00f3n del administrador y derecho comunitario","datePublished":"2022-06-11T09:18:54+00:00","dateModified":"2022-07-11T09:19:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ideolegal.com\/retribucion-del-administrador-y-derecho-comunitario\/"},"wordCount":1084,"publisher":{"@id":"https:\/\/www.ideolegal.com\/#organization"},"image":{"@id":"https:\/\/www.ideolegal.com\/retribucion-del-administrador-y-derecho-comunitario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ideolegal.com\/wp-content\/uploads\/mision.jpg","articleSection":["Sin categorizar"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.ideolegal.com\/retribucion-del-administrador-y-derecho-comunitario\/","url":"https:\/\/www.ideolegal.com\/retribucion-del-administrador-y-derecho-comunitario\/","name":"Retribuci\u00f3n del administrador y derecho comunitario - IDEO LEGAL Abogados especialistas en Derecho Financiero y Tributario en Madrid y M\u00e1laga","isPartOf":{"@id":"https:\/\/www.ideolegal.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ideolegal.com\/retribucion-del-administrador-y-derecho-comunitario\/#primaryimage"},"image":{"@id":"https:\/\/www.ideolegal.com\/retribucion-del-administrador-y-derecho-comunitario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ideolegal.com\/wp-content\/uploads\/mision.jpg","datePublished":"2022-06-11T09:18:54+00:00","dateModified":"2022-07-11T09:19:09+00:00","breadcrumb":{"@id":"https:\/\/www.ideolegal.com\/retribucion-del-administrador-y-derecho-comunitario\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ideolegal.com\/retribucion-del-administrador-y-derecho-comunitario\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ideolegal.com\/retribucion-del-administrador-y-derecho-comunitario\/#primaryimage","url":"https:\/\/www.ideolegal.com\/wp-content\/uploads\/mision.jpg","contentUrl":"https:\/\/www.ideolegal.com\/wp-content\/uploads\/mision.jpg","width":1920,"height":1280,"caption":"Ideo Legal"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ideolegal.com\/retribucion-del-administrador-y-derecho-comunitario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ideolegal.com\/en\/"},{"@type":"ListItem","position":2,"name":"Retribuci\u00f3n del administrador y derecho comunitario"}]},{"@type":"WebSite","@id":"https:\/\/www.ideolegal.com\/#website","url":"https:\/\/www.ideolegal.com\/","name":"IDEO LEGAL","description":"Abogados especialistas en Derecho Financiero y Tributario en Madrid y M\u00e1laga","publisher":{"@id":"https:\/\/www.ideolegal.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ideolegal.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.ideolegal.com\/#organization","name":"IDEO LEGAL","url":"https:\/\/www.ideolegal.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ideolegal.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.ideolegal.com\/wp-content\/uploads\/ideo_legal-logo-new.png","contentUrl":"https:\/\/www.ideolegal.com\/wp-content\/uploads\/ideo_legal-logo-new.png","width":350,"height":86,"caption":"IDEO LEGAL"},"image":{"@id":"https:\/\/www.ideolegal.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ideolegal.com\/#\/schema\/person\/ffc2742489f74493875a911a107a10df","name":"Ideo Legal","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/0ebca4407bb57b0c9696bad57a7fe578bcde74bb5214811efd0a85629c7e224c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0ebca4407bb57b0c9696bad57a7fe578bcde74bb5214811efd0a85629c7e224c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0ebca4407bb57b0c9696bad57a7fe578bcde74bb5214811efd0a85629c7e224c?s=96&d=mm&r=g","caption":"Ideo Legal"},"url":"https:\/\/www.ideolegal.com\/en\/author\/dcastro\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ideolegal.com\/en\/wp-json\/wp\/v2\/posts\/2775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ideolegal.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ideolegal.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ideolegal.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ideolegal.com\/en\/wp-json\/wp\/v2\/comments?post=2775"}],"version-history":[{"count":1,"href":"https:\/\/www.ideolegal.com\/en\/wp-json\/wp\/v2\/posts\/2775\/revisions"}],"predecessor-version":[{"id":2776,"href":"https:\/\/www.ideolegal.com\/en\/wp-json\/wp\/v2\/posts\/2775\/revisions\/2776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ideolegal.com\/en\/wp-json\/wp\/v2\/media\/2045"}],"wp:attachment":[{"href":"https:\/\/www.ideolegal.com\/en\/wp-json\/wp\/v2\/media?parent=2775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ideolegal.com\/en\/wp-json\/wp\/v2\/categories?post=2775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ideolegal.com\/en\/wp-json\/wp\/v2\/tags?post=2775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}